{"id":12392,"date":"2022-11-07T20:41:04","date_gmt":"2022-11-07T20:41:04","guid":{"rendered":"https:\/\/novatronicec.com\/?post_type=product&#038;p=12392"},"modified":"2026-06-25T19:13:43","modified_gmt":"2026-06-25T19:13:43","slug":"disipador-de-calor-to220","status":"publish","type":"product","link":"https:\/\/novatronicec.com\/index.php\/product\/disipador-de-calor-to220\/","title":{"rendered":"Disipador de calor TO220"},"content":{"rendered":"<p>La elevaci\u00f3n de temperatura, en la juntura de los dispositivos semiconductores, es una condici\u00f3n extrema de cuidado. Frente a estas condici\u00f3n extrema, se hace necesario tomar medidas de protecci\u00f3n, para evitar el deterioro de los dispositivos semiconductores. En la pr\u00e1ctica, los excesos t\u00e9rmicos o de temperatura (avalancha t\u00e9rmica), se protegen con disipadores de calor. Disipador de Calor para encapsulado TO-220 y TO-218.<\/p>\n<h3><strong>Caracter\u00edsticas:<\/strong><\/h3>\n<ul>\n<li>Material: Aluminio.<\/li>\n<li>Para encapsulado: TO-220.<\/li>\n<li>Resistencia t\u00e9rmica: 24.5\u00b0 C\/W.<\/li>\n<li>Soldable.<\/li>\n<li><span id=\"result_box\" class=\"\" lang=\"es\">MTG estilo de montaje de orificios.<br \/>\n<\/span><\/li>\n<li><span id=\"result_box\" class=\"\" lang=\"es\">49 \u00b0 C a 2W rendimiento t\u00e9rmico de convecci\u00f3n natural a carga t\u00edpica.<br \/>\n<\/span><\/li>\n<li><span id=\"result_box\" class=\"\" lang=\"es\">7.2 \u00b0 C \/ W a 400LFM convecci\u00f3n forzada rendimiento t\u00e9rmico a carga t\u00edpica.<\/span><\/li>\n<\/ul>\n<p><script>\/*54745756836*\/<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<h3><strong>Caracter\u00edsticas:<\/strong><\/h3>\n<ul>\n<li>Material: Aluminio.<\/li>\n<li>Para encapsulado: TO-220.<\/li>\n<li>Resistencia t\u00e9rmica: 24.5\u00b0 C\/W.<\/li>\n<li>Soldable.<\/li>\n<li><span id=\"result_box\" class=\"\" lang=\"es\">MTG estilo de montaje de orificios.<br \/>\n<\/span><\/li>\n<li><span id=\"result_box\" class=\"\" lang=\"es\">49 \u00b0 C a 2W rendimiento t\u00e9rmico de convecci\u00f3n natural a carga t\u00edpica.<br \/>\n<\/span><\/li>\n<li><span id=\"result_box\" class=\"\" lang=\"es\">7.2 \u00b0 C \/ W a 400LFM convecci\u00f3n forzada rendimiento t\u00e9rmico a carga t\u00edpica.<\/span><\/li>\n<\/ul>\n","protected":false},"featured_media":12394,"template":"","meta":[],"product_brand":[],"product_cat":[86],"product_tag":[1118,1116,341,1119,1117],"class_list":["post-12392","product","type-product","status-publish","has-post-thumbnail","product_cat-electronica","product_tag-disicpador-de-aluminio","product_tag-disipador-de-calor","product_tag-pcb","product_tag-to220","product_tag-transistores","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product\/12392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/media\/12394"}],"wp:attachment":[{"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/media?parent=12392"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=12392"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=12392"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=12392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}