{"id":17668,"date":"2025-10-03T19:32:43","date_gmt":"2025-10-03T19:32:43","guid":{"rendered":"https:\/\/novatronicec.com\/?post_type=product&#038;p=17668"},"modified":"2026-05-19T16:24:40","modified_gmt":"2026-05-19T16:24:40","slug":"filamento-petg-sunlu-rainbow-1kg","status":"publish","type":"product","link":"https:\/\/novatronicec.com\/index.php\/product\/filamento-petg-sunlu-rainbow-1kg\/","title":{"rendered":"Filamento PETG Sunlu Rainbow 1Kg"},"content":{"rendered":"<div class=\"text-title\" data-id=\"left-title\">\n<table style=\"height: 903px;\" width=\"977\">\n<tbody>\n<tr>\n<td width=\"189\"><img decoding=\"async\" src=\"https:\/\/cdn.shopify.com\/s\/files\/1\/0152\/6507\/1190\/files\/1_3c0ab609-fe46-4bd9-92f6-7dfde3c3b34c_540x.jpg?v=1668173324\" \/><\/p>\n<h3 class=\"h4 mg__0\">Alineaci\u00f3n ordenada, sin burbujas<\/h3>\n<p class=\"h4 mg__0\"><span style=\"font-family: inherit; font-size: inherit; color: #333333;\">Sin enredos, lo que garantiza una impresi\u00f3n uniforme en todo momento.<\/span><\/p>\n<\/td>\n<td width=\"189\"><img decoding=\"async\" src=\"https:\/\/cdn.shopify.com\/s\/files\/1\/0152\/6507\/1190\/files\/2_c0832bc2-30a8-46c1-b732-bc669225dd6a_540x.jpg?v=1668173339\" \/><\/p>\n<h3 class=\"h4 mg__0\">Sin obstruir<\/h3>\n<div class=\"rte-setting mt__7\">\n<p>Disfrute de una suave extrusi\u00f3n del filamento y un flujo de creaci\u00f3n delicado.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/td>\n<td width=\"189\"><img decoding=\"async\" src=\"https:\/\/cdn.shopify.com\/s\/files\/1\/0152\/6507\/1190\/files\/3_ea7a5896-c9c2-4d13-8f77-da7c276dc88f_540x.jpg?v=1668173355\" \/><\/p>\n<h3 class=\"h4 mg__0\">Precisi\u00f3n perfecta<\/h3>\n<div class=\"rte-setting mt__7\">\n<p>1,75 mm con una precisi\u00f3n \u00b10.02mm, imprime trabajos delicados con ricos detalles se pueden imprimir f\u00e1cilmente.<\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"189\"><img decoding=\"async\" src=\"https:\/\/cdn.shopify.com\/s\/files\/1\/0152\/6507\/1190\/files\/4_8aae4790-b07c-4577-bd8d-534b470e9b87_540x.jpg?v=1668173373\" \/><\/p>\n<h3 class=\"h4 mg__0\">Compatibilidad de impresoras<\/h3>\n<div class=\"rte-setting mt__7\">\n<p>Compatible con todas las impresoras SUNLU y la mayor\u00eda de impresoras 3D FDM del mercado.<\/p>\n<\/div>\n<\/td>\n<td width=\"189\">\n<h3><img decoding=\"async\" src=\"https:\/\/cdn.shopify.com\/s\/files\/1\/0152\/6507\/1190\/files\/6_68dda491-3139-4844-9c99-bcceebb0c7f2_540x.jpg?v=1668173389\" \/><\/h3>\n<h3 class=\"h4 mg__0\">Multicolor<\/h3>\n<div class=\"rte-setting mt__7\">\n<p>Los colores brillantes del arco\u00edris hacen que su impresi\u00f3n sea m\u00e1s atractiva y \u00fanica.<\/p>\n<\/div>\n<\/td>\n<td width=\"189\">&nbsp;<\/p>\n<h3><img decoding=\"async\" src=\"https:\/\/cdn.shopify.com\/s\/files\/1\/0152\/6507\/1190\/files\/5_cacd5b29-fc2b-4530-a315-2a3f0fbeb062_540x.jpg?v=1668173405\" \/><\/h3>\n<h3 class=\"h4 mg__0\">Respetuoso del medio ambiente<\/h3>\n<p class=\"h4 mg__0\"><span style=\"font-family: inherit; font-size: inherit; color: #333333;\">Es degradable y cumple con RoHS, <\/span><span style=\"font-family: inherit; font-size: inherit;\">que est\u00e1n hechos de almid\u00f3n vegetal fermentado.<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"text-content\" data-id=\"left-content\">\n<h4 class=\"magic-20\"><b>CARACTER\u00cdSTICAS<\/b><\/h4>\n<ul>\n<li>Di\u00e1metro:\u00a01.75mm<\/li>\n<li>Temperatura de impresi\u00f3n sugerida:\u00a0230-260\u00b0C<\/li>\n<li>Temperatura de la cama:\u00a060-70\u00b0C<\/li>\n<li>Tolerancia:\u00a0\u00b10.02mm<\/li>\n<li>Peso:\u00a01Kg<\/li>\n<li>Libre de enredos<\/li>\n<li>Material de excelente calidad<\/li>\n<li>Alta compatibilidad con impresoras 3D FDM<\/li>\n<li>Empaque sellado al vac\u00edo<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<h4 class=\"magic-20\"><b>CARACTER\u00cdSTICAS:<\/b><\/h4>\n<ul>\n<li>Di\u00e1metro:\u00a01.75mm<\/li>\n<li>Temperatura de impresi\u00f3n sugerida:\u00a0230-260\u00b0C<\/li>\n<li>Temperatura de la cama:\u00a060-70\u00b0C<\/li>\n<li>Tolerancia:\u00a0\u00b10.02mm<\/li>\n<li>Peso:\u00a01Kg<\/li>\n<li>Libre de enredos<\/li>\n<li>Material de excelente calidad<\/li>\n<li>Alta compatibilidad con impresoras 3D FDM<\/li>\n<li>Empaque sellado al vac\u00edo<\/li>\n<\/ul>\n","protected":false},"featured_media":17670,"template":"","meta":[],"product_brand":[],"product_cat":[87,76],"product_tag":[868,801,800,870,875,869],"class_list":["post-17668","product","type-product","status-publish","has-post-thumbnail","product_cat-filamentos","product_cat-insumos-para-impresion-3d","product_tag-arcoiris","product_tag-impresion-3d","product_tag-material-de-impresion","product_tag-multicolor","product_tag-petg","product_tag-rainbow","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product\/17668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/media\/17670"}],"wp:attachment":[{"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/media?parent=17668"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=17668"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=17668"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=17668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}