{"id":17803,"date":"2026-01-16T21:53:52","date_gmt":"2026-01-16T21:53:52","guid":{"rendered":"https:\/\/novatronicec.com\/?post_type=product&#038;p=17803"},"modified":"2026-03-20T17:07:27","modified_gmt":"2026-03-20T17:07:27","slug":"bateria-lipo-850mah-3s-11-1v-45c-tattu-xt30","status":"publish","type":"product","link":"https:\/\/novatronicec.com\/index.php\/product\/bateria-lipo-850mah-3s-11-1v-45c-tattu-xt30\/","title":{"rendered":"BATERIA LIPO 850mAh 3S 11.1V 45C TATTU XT30"},"content":{"rendered":"<h4>DESCRIPCI\u00d3N:<\/h4>\n<p>Las Bater\u00edas LiPo Tattu han sido desarrolladas especialmente para el mercado de UAV y UAS. Su eslogan es \u00abmenos es m\u00e1s\u00bb: \u00abm\u00e1s\u00bb por mayor tiempo de vuelo, m\u00e1s disfrute y m\u00e1s satisfacci\u00f3n; \u00abmenos\u00bb se refiere al peso ligero y al dise\u00f1o simple. Tattu siempre desarrolla sus productos siguiendo estos ideales, ofreci\u00e9ndote una bater\u00eda de alta calidad. Las bater\u00edas Tattu se emparejan utilizando un proceso de emparejamiento autom\u00e1tico por computadora que asegura la estabilidad y calidad de la bater\u00eda.<\/p>\n<h4>CARACTER\u00cdSTICAS:<\/h4>\n<ul>\n<li>Capacidad (mAh):\u00a0850<\/li>\n<li>Voltaje (V): 11.1<\/li>\n<li>Tasa de Descarga (C): 45<\/li>\n<li>Tasa M\u00e1xima de Descarga de R\u00e1faga (C): 90<\/li>\n<li>Peso Neto (g): 78<\/li>\n<li>Largo (\u00b15mm): 57<\/li>\n<li>Ancho (\u00b12mm): 30<\/li>\n<li>Alto (\u00b12mm): 23<\/li>\n<li>Tipo de Conector: XT-30<\/li>\n<li>Calibre del Cable:\u00a0\u00a016 AWG<\/li>\n<li>Tipo de Conector de Balanceo:\u00a0JST-XHR<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<h4>CARACTER\u00cdSTICAS:<\/h4>\n<ul>\n<li>Capacidad (mAh):\u00a0850<\/li>\n<li>Voltaje (V): 11.1<\/li>\n<li>Tasa de Descarga (C): 45<\/li>\n<li>Tasa M\u00e1xima de Descarga de R\u00e1faga (C): 90<\/li>\n<li>Peso Neto (g): 78<\/li>\n<li>Largo (\u00b15mm): 57<\/li>\n<li>Ancho (\u00b12mm): 30<\/li>\n<li>Alto (\u00b12mm): 23<\/li>\n<li>Tipo de Conector: XT-30<\/li>\n<li>Calibre del Cable:\u00a0\u00a016 AWG<\/li>\n<li>Tipo de Conector de Balanceo:\u00a0JST-XHR<\/li>\n<\/ul>\n","protected":false},"featured_media":17823,"template":"","meta":[],"product_brand":[],"product_cat":[128,86],"product_tag":[131,713,130,129,136,134],"class_list":["post-17803","product","type-product","status-publish","has-post-thumbnail","product_cat-baterias","product_cat-electronica","product_tag-bateria","product_tag-bateria-recargable","product_tag-baterialipo","product_tag-lipo","product_tag-robot","product_tag-tattu","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product\/17803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/media\/17823"}],"wp:attachment":[{"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/media?parent=17803"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=17803"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=17803"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/novatronicec.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=17803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}